{"id":4992,"date":"2026-04-22T12:51:21","date_gmt":"2026-04-22T16:51:21","guid":{"rendered":"https:\/\/technosylva.com\/?post_type=news&#038;p=4992"},"modified":"2026-05-01T16:21:21","modified_gmt":"2026-05-01T20:21:21","slug":"technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2","status":"publish","type":"news","link":"https:\/\/technosylva.com\/es\/news\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\/","title":{"rendered":"Technosylva y Pano AI anuncian un acuerdo de colaboraci\u00f3n para ofrecer informaci\u00f3n unificada, predictiva y en tiempo real sobre incendios forestales a empresas de servicios p\u00fablicos y bomberos"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1018\" height=\"386\" src=\"https:\/\/technosylva.com\/wp-content\/uploads\/2026\/02\/techno_pano-1.jpg\" alt=\"\" class=\"wp-image-4487\" srcset=\"https:\/\/technosylva.com\/wp-content\/uploads\/2026\/02\/techno_pano-1.jpg 1018w, https:\/\/technosylva.com\/wp-content\/uploads\/2026\/02\/techno_pano-1-300x114.jpg 300w, https:\/\/technosylva.com\/wp-content\/uploads\/2026\/02\/techno_pano-1-768x291.jpg 768w\" sizes=\"auto, (max-width: 1018px) 100vw, 1018px\" \/><\/figure>\n<\/div><div data-technosylva-block  class=\"py-20 rich-text-block\">\n\t<div class=\"container space-y-10\">\n\t\t<div class=\"mx-auto rich-text\">\n\t\t\t<div class=\"acf-innerblocks-container\">\n\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>Las nuevas integraciones t\u00e9cnicas conectar\u00e1n los modelos predictivos de riesgo y propagaci\u00f3n de incendios forestales de Technosylva con la detecci\u00f3n en tiempo real y la inteligencia de incidentes de Pano AI, uniendo la confirmaci\u00f3n visual de incidentes y el an\u00e1lisis prospectivo para respaldar decisiones m\u00e1s r\u00e1pidas e informadas sobre los riesgos.<\/strong><\/h4>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>LA JOLLA, California y SAN FRANCISCO, California &#8211; 3 de febrero de 2026 <\/strong>&#8211; Technosylva y Pano AI han anunciado hoy una asociaci\u00f3n estrat\u00e9gica para ofrecer una visi\u00f3n m\u00e1s unificada y simplificada del riesgo de incendios forestales y de los incidentes activos a las empresas de servicios p\u00fablicos, los cuerpos de bomberos y los primeros intervinientes que utilicen -o tengan previsto utilizar- ambas tecnolog\u00edas. Combinando el an\u00e1lisis predictivo de riesgos y sucesos de incendios forestales de Technosylva con las vistas de c\u00e1maras en directo y la inteligencia de ignici\u00f3n de Pano AI, las empresas pretenden ayudar a los equipos operativos a pasar de sistemas separados y contextos fragmentados a una imagen compartida y preparada para la toma de decisiones que conecte lo que est\u00e1 ocurriendo ahora con lo que puede ocurrir a continuaci\u00f3n. <\/p>\n\n\n\n<p>Las operaciones contra incendios forestales exigen cada vez m\u00e1s decisiones r\u00e1pidas en condiciones de incertidumbre, y los equipos a menudo deben conciliar las previsiones predictivas, las actualizaciones de incidentes y la confirmaci\u00f3n sobre el terreno a trav\u00e9s de diferentes herramientas y flujos de trabajo. Mediante esta asociaci\u00f3n, Technosylva y Pano AI est\u00e1n construyendo integraciones t\u00e9cnicas que llevan la confirmaci\u00f3n visual del humo y la inteligencia de incidentes de Pano directamente al software de modelizaci\u00f3n y riesgo de incendios forestales de Technosylva, al tiempo que permiten que las simulaciones y proyecciones de Technosylva salgan a la superficie dentro del entorno de gesti\u00f3n de incidentes de Pano. El resultado pretende ofrecer a los usuarios un apoyo basado en IA en ambos lados de la ecuaci\u00f3n operativa: inteligencia predictiva de Technosylva para anticiparse a las condiciones cambiantes y al posible comportamiento del fuego, y monitorizaci\u00f3n en tiempo real e inteligencia de incidentes de Pano AI para confirmar las igniciones y seguir la evoluci\u00f3n de la actividad sobre el terreno.  <\/p>\n\n\n\n<p>\u00abEstamos trabajando para facilitar que las empresas de servicios p\u00fablicos y los organismos se alineen en la misma imagen operativa, combinando el est\u00e1ndar del sector para el modelado predictivo de incendios forestales con la visibilidad de incidentes en tiempo real habilitada por IA, de modo que los equipos puedan coordinarse antes y actuar con mayor confianza a medida que cambian las condiciones\u00bb, dijo <strong>Michael McGuire, Director Comercial<\/strong> de Technosylva. \u00abCuando puedes ver el riesgo y el comportamiento previsto junto con el contexto verificado y en tiempo real del incidente, se refuerza la toma de decisiones en la planificaci\u00f3n, las operaciones y la respuesta\u00bb. <\/p>\n\n\n\n<p>\u00abLa detecci\u00f3n precoz y el conocimiento compartido de la situaci\u00f3n son fundamentales para reducir el tiempo de respuesta y mejorar la coordinaci\u00f3n\u00bb, afirma <strong>Arvind Satyam<\/strong>, <strong>cofundador y director comercial<\/strong> de Pano AI. \u00abAl conectar la inteligencia visual y el conocimiento de la situaci\u00f3n de Pano con el an\u00e1lisis predictivo de Technosylva, estamos ayudando a los equipos a reunir lo que est\u00e1n viendo ahora con lo que los datos sugieren que podr\u00eda desarrollarse a continuaci\u00f3n, para que puedan planificar los recursos, comunicarse con claridad y responder con mayor eficacia.\u00bb <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Las empresas de servicios p\u00fablicos han adoptado cada vez m\u00e1s tanto la modelizaci\u00f3n predictiva como la detecci\u00f3n en tiempo real para reforzar los programas de mitigaci\u00f3n de incendios forestales, y esta asociaci\u00f3n est\u00e1 dise\u00f1ada para que ese flujo de trabajo combinado sea m\u00e1s sencillo de utilizar en las operaciones cotidianas y durante los incidentes.<\/p>\n<\/blockquote>\n\n\n\n<p>Reflejando el valor de un enfoque unificado, <strong>Paul McGregor, Vicepresidente de Gesti\u00f3n de Riesgos de Incendios Forestales de Xcel<\/strong> Energy, dijo: \u00abUnir el modelado predictivo de Technosylva con la visibilidad en tiempo real de Pano AI ayuda a nuestros equipos a conectar las condiciones de riesgo con lo que est\u00e1 ocurriendo realmente sobre el terreno. Esa imagen compartida puede mejorar la coordinaci\u00f3n entre nuestras operaciones y con los organismos de respuesta, permitiendo tomar decisiones m\u00e1s r\u00e1pidas y seguras a medida que evolucionan los incidentes\u00bb.<\/p>\n\n\n\n<p>A medida que las empresas de servicios p\u00fablicos y las agencias se enfrentan a temporadas de incendios m\u00e1s largas, condiciones meteorol\u00f3gicas extremas m\u00e1s frecuentes y mayores expectativas en torno a la mitigaci\u00f3n y respuesta a los incendios forestales, la inteligencia integrada predictiva y en tiempo real se est\u00e1 convirtiendo en algo esencial para las operaciones modernas de las empresas de servicios p\u00fablicos. Esta asociaci\u00f3n apoyar\u00e1 los flujos de trabajo operativos comunes para las empresas de servicios p\u00fablicos, las agencias de bomberos y los equipos de incidentes, incluyendo una alineaci\u00f3n m\u00e1s r\u00e1pida entre las partes interesadas, comunicaciones m\u00e1s claras entre los centros de operaciones y la respuesta sobre el terreno, y una estrategia de incidentes y una planificaci\u00f3n de recursos m\u00e1s informadas a medida que las condiciones meteorol\u00f3gicas, los combustibles, el terreno y las acciones de extinci\u00f3n interact\u00faan con el tiempo. Technosylva y Pano AI esperan que la integraci\u00f3n del modelado predictivo con la inteligencia en vivo en un flujo de trabajo \u00fanico y coordinado se convierta r\u00e1pidamente en la mejor pr\u00e1ctica para la lucha contra incendios y la gesti\u00f3n de incidentes. Las empresas trabajar\u00e1n con clientes mutuos seleccionados para validar los despliegues y perfeccionar los hitos de integraci\u00f3n antes de una disponibilidad m\u00e1s amplia.   <\/p>\n\n\n\n<p><\/p>\n\n<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div data-technosylva-block  class=\"py-20 rich-text-block\">\n\t<div class=\"container space-y-10\">\n\t\t<div class=\"mx-auto rich-text\">\n\t\t\t<div class=\"acf-innerblocks-container\">\n\n<h4 class=\"wp-block-heading\">Acerca de Technosylva<\/h4>\n\n\n\n<p>Technosylva es la plataforma multiriesgo est\u00e1ndar del sector para la ciencia de incendios forestales y condiciones meteorol\u00f3gicas extremas, en la que conf\u00edan las empresas de servicios p\u00fablicos y los cuerpos de bomberos de todo el mundo para planificar y responder a las amenazas en tiempo real. Impulsada por d\u00e9cadas de ciencia probada e IA, Technosylva proporciona datos de alta calidad y perspectivas procesables que ayudan a las organizaciones a tomar decisiones seguras, apoyando la mitigaci\u00f3n de riesgos, la preparaci\u00f3n operativa y la respuesta de emergencia para reducir el impacto de los incendios forestales y el clima extremo en las comunidades. Fundada en 1997, Technosylva tiene oficinas en La Jolla (California) y Le\u00f3n (Espa\u00f1a). Para m\u00e1s informaci\u00f3n, visita <a href=\"http:\/\/www.technosylva.com\">www.technosylva.com<\/a> o s\u00edguenos en <a href=\"https:\/\/www.linkedin.com\/company\/technosylva\/posts\/?feedView=all\">LinkedIn<\/a>.   <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Acerca de Pano AI<\/h4>\n\n\n\n<p>Pano AI es el l\u00edder en detecci\u00f3n de incendios forestales basada en IA. Lanzada en 2020, la empresa ofrece soluciones avanzadas de detecci\u00f3n precoz y conocimiento de la situaci\u00f3n a cuerpos de bomberos, empresas de servicios p\u00fablicos, gobiernos y propietarios privados para ayudar a proteger a las personas, los bienes y las infraestructuras de los incendios catastr\u00f3ficos. Con despliegues en EE.UU., Canad\u00e1 y Australia, Pano AI est\u00e1 construyendo un nuevo est\u00e1ndar de inteligencia en tiempo real sobre incendios forestales. Para m\u00e1s informaci\u00f3n, visita <a href=\"http:\/\/www.pano.ai\">www.pano.ai<\/a> o sigue a la empresa en <a href=\"https:\/\/www.linkedin.com\/company\/pano-ai\/\">LinkedIn<\/a>.   <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Contactos<\/h4>\n\n\n\n<h5 class=\"wp-block-heading\">Medios de comunicaci\u00f3n<\/h5>\n\n\n\n<p><strong>Para Technosylva<\/strong><\/p>\n\n\n\n<p>Technosylva<br\/>Lucian Deaton<br\/>Director Senior de Marketing Digital<br\/><a href=\"mailto:ldeaton@technosylva.com\">ldeaton@technosylva.com<\/a><\/p>\n\n\n\n<p>Mahoney Communications Group<br\/>Daysa Corrington<br\/><a href=\"mailto:Daysa@MahoneyCommunications.com\">Daysa@MahoneyCommunications.com<\/a><br\/>(212) 220-6045<\/p>\n\n\n\n<p><strong>Pano IA<\/strong><\/p>\n\n\n\n<p>Jennifer Spoerri<br\/><a href=\"mailto:jennifer.spoerri@pano.ai\">jennifer.spoerri@pano.ai<\/a><br\/>(415) 577-0171<\/p>\n\n<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n","protected":false},"template":"","news-category":[73],"class_list":["post-4992","news","type-news","status-publish","hentry","news-category-press-release"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Technosylva y Pano AI anuncian un acuerdo de colaboraci\u00f3n para ofrecer informaci\u00f3n unificada, predictiva y en tiempo real sobre incendios forestales a empresas de servicios p\u00fablicos y bomberos - Technosylva<\/title>\n<meta name=\"description\" content=\"Technosylva y Pano AI han anunciado hoy una asociaci\u00f3n estrat\u00e9gica para ofrecer una visi\u00f3n m\u00e1s unificada y simplificada del riesgo de incendios forestales y de los incidentes activos a las empresas de servicios p\u00fablicos, los cuerpos de bomberos y los primeros intervinientes que utilicen -o tengan previsto utilizar- ambas tecnolog\u00edas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/technosylva.com\/es\/news\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Technosylva y Pano AI anuncian un acuerdo de colaboraci\u00f3n para ofrecer informaci\u00f3n unificada, predictiva y en tiempo real sobre incendios forestales a empresas de servicios p\u00fablicos y bomberos - Technosylva\" \/>\n<meta name=\"twitter:description\" content=\"Technosylva y Pano AI han anunciado hoy una asociaci\u00f3n estrat\u00e9gica para ofrecer una visi\u00f3n m\u00e1s unificada y simplificada del riesgo de incendios forestales y de los incidentes activos a las empresas de servicios p\u00fablicos, los cuerpos de bomberos y los primeros intervinientes que utilicen -o tengan previsto utilizar- ambas tecnolog\u00edas.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/technosylva.com\/wp-content\/uploads\/2026\/02\/techno_pano-1.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@technosylva\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/technosylva.com\\\/es\\\/news\\\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\\\/\",\"url\":\"https:\\\/\\\/technosylva.com\\\/es\\\/news\\\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\\\/\",\"name\":\"Technosylva y Pano AI anuncian un acuerdo de colaboraci\u00f3n para ofrecer informaci\u00f3n unificada, predictiva y en tiempo real sobre incendios forestales a empresas de servicios p\u00fablicos y bomberos - Technosylva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/technosylva.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/technosylva.com\\\/es\\\/news\\\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/technosylva.com\\\/es\\\/news\\\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/technosylva.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/techno_pano-1.jpg\",\"datePublished\":\"2026-04-22T16:51:21+00:00\",\"dateModified\":\"2026-05-01T20:21:21+00:00\",\"description\":\"Technosylva y Pano AI han anunciado hoy una asociaci\u00f3n estrat\u00e9gica para ofrecer una visi\u00f3n m\u00e1s unificada y simplificada del riesgo de incendios forestales y de los incidentes activos a las empresas de servicios p\u00fablicos, los cuerpos de bomberos y los primeros intervinientes que utilicen -o tengan previsto utilizar- ambas tecnolog\u00edas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/technosylva.com\\\/es\\\/news\\\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/technosylva.com\\\/es\\\/news\\\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/technosylva.com\\\/es\\\/news\\\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/technosylva.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/techno_pano-1.jpg\",\"contentUrl\":\"https:\\\/\\\/technosylva.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/techno_pano-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/technosylva.com\\\/es\\\/news\\\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/technosylva.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Technosylva y Pano AI anuncian un acuerdo de colaboraci\u00f3n para ofrecer informaci\u00f3n unificada, predictiva y en tiempo real sobre incendios forestales a empresas de servicios p\u00fablicos y bomberos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/technosylva.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/technosylva.com\\\/es\\\/\",\"name\":\"Technosylva\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/technosylva.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/technosylva.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/technosylva.com\\\/es\\\/#organization\",\"name\":\"Technosylva\",\"url\":\"https:\\\/\\\/technosylva.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/technosylva.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/technosylva.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/technosylva.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Technosylva\"},\"image\":{\"@id\":\"https:\\\/\\\/technosylva.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/technosylva\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/technosylva\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Technosylva y Pano AI anuncian un acuerdo de colaboraci\u00f3n para ofrecer informaci\u00f3n unificada, predictiva y en tiempo real sobre incendios forestales a empresas de servicios p\u00fablicos y bomberos - Technosylva","description":"Technosylva y Pano AI han anunciado hoy una asociaci\u00f3n estrat\u00e9gica para ofrecer una visi\u00f3n m\u00e1s unificada y simplificada del riesgo de incendios forestales y de los incidentes activos a las empresas de servicios p\u00fablicos, los cuerpos de bomberos y los primeros intervinientes que utilicen -o tengan previsto utilizar- ambas tecnolog\u00edas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/technosylva.com\/es\/news\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\/","twitter_card":"summary_large_image","twitter_title":"Technosylva y Pano AI anuncian un acuerdo de colaboraci\u00f3n para ofrecer informaci\u00f3n unificada, predictiva y en tiempo real sobre incendios forestales a empresas de servicios p\u00fablicos y bomberos - Technosylva","twitter_description":"Technosylva y Pano AI han anunciado hoy una asociaci\u00f3n estrat\u00e9gica para ofrecer una visi\u00f3n m\u00e1s unificada y simplificada del riesgo de incendios forestales y de los incidentes activos a las empresas de servicios p\u00fablicos, los cuerpos de bomberos y los primeros intervinientes que utilicen -o tengan previsto utilizar- ambas tecnolog\u00edas.","twitter_image":"https:\/\/technosylva.com\/wp-content\/uploads\/2026\/02\/techno_pano-1.jpg","twitter_site":"@technosylva","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/technosylva.com\/es\/news\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\/","url":"https:\/\/technosylva.com\/es\/news\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\/","name":"Technosylva y Pano AI anuncian un acuerdo de colaboraci\u00f3n para ofrecer informaci\u00f3n unificada, predictiva y en tiempo real sobre incendios forestales a empresas de servicios p\u00fablicos y bomberos - Technosylva","isPartOf":{"@id":"https:\/\/technosylva.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/technosylva.com\/es\/news\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\/#primaryimage"},"image":{"@id":"https:\/\/technosylva.com\/es\/news\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\/#primaryimage"},"thumbnailUrl":"https:\/\/technosylva.com\/wp-content\/uploads\/2026\/02\/techno_pano-1.jpg","datePublished":"2026-04-22T16:51:21+00:00","dateModified":"2026-05-01T20:21:21+00:00","description":"Technosylva y Pano AI han anunciado hoy una asociaci\u00f3n estrat\u00e9gica para ofrecer una visi\u00f3n m\u00e1s unificada y simplificada del riesgo de incendios forestales y de los incidentes activos a las empresas de servicios p\u00fablicos, los cuerpos de bomberos y los primeros intervinientes que utilicen -o tengan previsto utilizar- ambas tecnolog\u00edas.","breadcrumb":{"@id":"https:\/\/technosylva.com\/es\/news\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/technosylva.com\/es\/news\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/technosylva.com\/es\/news\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\/#primaryimage","url":"https:\/\/technosylva.com\/wp-content\/uploads\/2026\/02\/techno_pano-1.jpg","contentUrl":"https:\/\/technosylva.com\/wp-content\/uploads\/2026\/02\/techno_pano-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/technosylva.com\/es\/news\/technosylva-y-pano-ai-anuncian-un-acuerdo-de-colaboracion-para-ofrecer-informacion-unificada-predictiva-y-en-tiempo-real-sobre-incendios-forestales-a-empresas-de-servicios-publicos-y-bomberos-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/technosylva.com\/es\/"},{"@type":"ListItem","position":2,"name":"Technosylva y Pano AI anuncian un acuerdo de colaboraci\u00f3n para ofrecer informaci\u00f3n unificada, predictiva y en tiempo real sobre incendios forestales a empresas de servicios p\u00fablicos y bomberos"}]},{"@type":"WebSite","@id":"https:\/\/technosylva.com\/es\/#website","url":"https:\/\/technosylva.com\/es\/","name":"Technosylva","description":"","publisher":{"@id":"https:\/\/technosylva.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/technosylva.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/technosylva.com\/es\/#organization","name":"Technosylva","url":"https:\/\/technosylva.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/technosylva.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/technosylva.com\/wp-content\/uploads\/2025\/08\/logo.svg","contentUrl":"https:\/\/technosylva.com\/wp-content\/uploads\/2025\/08\/logo.svg","width":1,"height":1,"caption":"Technosylva"},"image":{"@id":"https:\/\/technosylva.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/technosylva","https:\/\/www.linkedin.com\/company\/technosylva"]}]}},"_links":{"self":[{"href":"https:\/\/technosylva.com\/es\/wp-json\/wp\/v2\/news\/4992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/technosylva.com\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/technosylva.com\/es\/wp-json\/wp\/v2\/types\/news"}],"wp:attachment":[{"href":"https:\/\/technosylva.com\/es\/wp-json\/wp\/v2\/media?parent=4992"}],"wp:term":[{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/technosylva.com\/es\/wp-json\/wp\/v2\/news-category?post=4992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}